{"id":8815,"date":"2024-06-08T16:23:39","date_gmt":"2024-06-08T16:23:39","guid":{"rendered":"https:\/\/hypnosis.plus\/index.php\/register\/edit-your-profile\/"},"modified":"2024-06-08T16:23:39","modified_gmt":"2024-06-08T16:23:39","slug":"edit-your-profile","status":"publish","type":"page","link":"https:\/\/hypnosis.plus\/index.php\/register\/edit-your-profile\/","title":{"rendered":"Edit Your Profile"},"content":{"rendered":"\n\n\t\n\t<form id=\"rcp_login_form\"  class=\"rcp_form\" method=\"POST\" action=\"https:\/\/hypnosis.plus\/wp-json\/wp\/v2\/pages\/8815\/\">\n\n\t\t\n\t\t<fieldset class=\"rcp_login_data\">\n\t\t\t<p>\n\t\t\t\t<label for=\"rcp_user_login\">Username or Email<\/label>\n\t\t\t\t<input name=\"rcp_user_login\" id=\"rcp_user_login\" class=\"required\" type=\"text\"\/>\n\t\t\t<\/p>\n\t\t\t<p>\n\t\t\t\t<label for=\"rcp_user_pass\">Password<\/label>\n\t\t\t\t<input name=\"rcp_user_pass\" id=\"rcp_user_pass\" class=\"required\" type=\"password\"\/>\n\t\t\t<\/p>\n\t\t\t\t\t\t<p>\n\t\t\t\t<input type=\"checkbox\" name=\"rcp_user_remember\" id=\"rcp_user_remember\" value=\"1\"\/>\n\t\t\t\t<label for=\"rcp_user_remember\">Remember me<\/label>\n\t\t\t<\/p>\n\t\t\t<p class=\"rcp_lost_password\"><a href=\"\/index.php\/wp-json\/wp\/v2\/pages\/8815?rcp_action=lostpassword\">Lost your password?<\/a><\/p>\n\t\t\t<p>\n\t\t\t\t<input type=\"hidden\" name=\"rcp_action\" value=\"login\"\/>\n\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"rcp_redirect\" value=\"https:\/\/hypnosis.plus\/wp-json\/wp\/v2\/pages\/8815\/\"\/>\n\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"rcp_login_nonce\" value=\"d364711875\"\/>\n\t\t\t\t<input id=\"rcp_login_submit\" class=\"rcp-button\" type=\"submit\" value=\"Login\"\/>\n\t\t\t<\/p>\n\t\t\t\t\t<\/fieldset>\n\n\t\t\n\t<\/form>\n\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"page\" \r\n\t            data-cat=\"\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1717863819\"\r\n\t            data-title=\"Edit Your Profile\" \r\n\t            data-home=\"https:\/\/hypnosis.plus\"><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":8812,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8815","page","type-page","status-publish"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/hypnosis.plus\/index.php\/wp-json\/wp\/v2\/pages\/8815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hypnosis.plus\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hypnosis.plus\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hypnosis.plus\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hypnosis.plus\/index.php\/wp-json\/wp\/v2\/comments?post=8815"}],"version-history":[{"count":0,"href":"https:\/\/hypnosis.plus\/index.php\/wp-json\/wp\/v2\/pages\/8815\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/hypnosis.plus\/index.php\/wp-json\/wp\/v2\/pages\/8812"}],"wp:attachment":[{"href":"https:\/\/hypnosis.plus\/index.php\/wp-json\/wp\/v2\/media?parent=8815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}